{"id":3425,"date":"2023-03-24T15:31:08","date_gmt":"2023-03-24T15:31:08","guid":{"rendered":"https:\/\/www.therapmedic.com\/product\/peeling-de-acido-phytico-phytic-peel-hollywood-style-peeling\/"},"modified":"2026-05-20T17:02:38","modified_gmt":"2026-05-20T17:02:38","slug":"peeling-de-acido-phytico-phytic-peel-hollywood-style-peeling","status":"publish","type":"product","link":"https:\/\/www.therapmedic.com\/fr\/produit\/peeling-de-acido-phytico-phytic-peel-hollywood-style-peeling\/","title":{"rendered":"Peeling de Acido Phytico &#8211; PHYTIC PEEL (Hollywood Style peeling)"},"content":{"rendered":"<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span class=\"Y2IQFc\" lang=\"pt\"><strong>AHA Peeling Phytico Peel (Hollywood Peel)<\/strong> &#8211; Propriedades antioxidantes, clareadoras e anti-inflamat\u00f3rias<\/span><\/p>\n<p>Estimula o processo regenerativo da pele e tem um efeito duradouro. Indicado para peles sens\u00edveis e sem restri\u00e7\u00f5es de uso.Ap\u00f3s o uso, hidratar com NUTRIPEEL EMULS\u00c3O e aplicar FPS 30 para proteger a pele renovada das agress\u00f5es do dia, todos os dias (n\u00e3o s\u00f3 em dias de sol).<\/p>\n<p>Apresenta\u00e7\u00e3o:<br \/>\nCaixa: conjunto de 2 frascos n\u00ba 1 e n\u00ba 2 cada um com 50 ml<\/p>\n<p>O pre\u00e7o apresentado \u00e9 para um conjunto de duas garrafas n\u00ba 1 e n\u00ba 2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AHA Peeling Phytico Peel (Hollywood Peel) &#8211; Propriedades antioxidantes, clareadoras e anti-inflamat\u00f3rias Estimula o processo regenerativo da pele e tem um efeito duradouro. Indicado para peles sens\u00edveis e sem restri\u00e7\u00f5es de uso.Ap\u00f3s o uso, hidratar com NUTRIPEEL EMULS\u00c3O e aplicar FPS 30 para proteger a pele renovada das agress\u00f5es do dia, todos os dias (n\u00e3o [&hellip;]<\/p>\n","protected":false},"featured_media":8945,"template":"","meta":[],"product_brand":[],"product_cat":[1283,1327,1265,1286,1328,1267,1287,1329,1269,1290,1331,1270,1291,2097,1271,1294,2099,1275,1296,2103,1279,1297,1280,1300,1281,1302,1282,1303,1100],"product_tag":[],"class_list":["post-3425","product","type-product","status-publish","has-post-thumbnail","product_cat-body-fr","product_cat-saggy-skin-6-fr","product_cat-melasmas-brown-spots-3-fr","product_cat-neckline-fr","product_cat-dull-skin-fr","product_cat-melasmas-brown-spots-7-fr","product_cat-gray-oxidized-skin-fr","product_cat-melasmas-brown-spots-hyperpigmentation-fr","product_cat-melasmas-brown-spots-5-fr","product_cat-face-fr","product_cat-skin-whitening-fr","product_cat-melasmas-brown-spots-6-fr","product_cat-aged-skin-fr","product_cat-aha-peelings-alpha-hydroxy-acids-fr","product_cat-melasmas-brown-spots-fr","product_cat-grey-oxidized-skin-fr","product_cat-peelings-fr-3","product_cat-melasmas-brown-spots-4-fr","product_cat-hands-fr","product_cat-phytic-acid-peels-fr","product_cat-arms-fr","product_cat-aged-skin-5-fr","product_cat-neck-fr","product_cat-treatment-areas-vs-products-fr","product_cat-aged-skin-4-fr","product_cat-buttocks-fr","product_cat-aged-skin-2-fr","product_cat-legs-fr","product_cat-acne-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":{"short_name":""},"_links":{"self":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product\/3425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/media\/8945"}],"wp:attachment":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/media?parent=3425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}