{"id":3263,"date":"2022-12-07T17:24:24","date_gmt":"2022-12-07T17:24:24","guid":{"rendered":"https:\/\/www.therapmedic.com\/product\/golden-skin\/"},"modified":"2026-05-08T17:22:27","modified_gmt":"2026-05-08T17:22:27","slug":"golden-skin","status":"publish","type":"product","link":"https:\/\/www.therapmedic.com\/fr\/produit\/golden-skin\/","title":{"rendered":"Golden Skin"},"content":{"rendered":"<p><b><i>Golden Skin <\/i><\/b><b>&#8211;\u00a0 <\/b>para clareamento da pele e elimina\u00e7\u00e3o de manchas castanhas na pele<\/p>\n<p>Manchas castanhas n\u00e3o s\u00e3o mais um problema. <b><i>Golden Skin <\/i><\/b>cont\u00e9m um diluente que inibe a produ\u00e7\u00e3o de Melanina atrav\u00e9s da Tirasinase. Cont\u00e9m um poderoso antioxidante que inibe o funcionamento do horm\u00f3nio que produz a melanina. Use-o para unificar o tom da pele, manchas de sol secas ou manchas de velhice.<\/p>\n<p>O Poder dos Peptideos na restaura\u00e7\u00e3o da sa\u00fade dasua pele depois dos maus tratos do sol e da polui\u00e7\u00e3o de anos.<\/p>\n<p>Apresenta\u00e7\u00e3o: Caixa de 5 conjuntos (vial de p\u00f3 e respetivo solvente)<\/p>\n<p>O pre\u00e7o apresentado \u00e9 por conjunto frasco de p\u00f3 + solvente espec\u00edfico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Golden Skin &#8211;\u00a0 para clareamento da pele e elimina\u00e7\u00e3o de manchas castanhas na pele Manchas castanhas n\u00e3o s\u00e3o mais um problema. Golden Skin cont\u00e9m um diluente que inibe a produ\u00e7\u00e3o de Melanina atrav\u00e9s da Tirasinase. Cont\u00e9m um poderoso antioxidante que inibe o funcionamento do horm\u00f3nio que produz a melanina. Use-o para unificar o tom da [&hellip;]<\/p>\n","protected":false},"featured_media":8729,"template":"","meta":[],"product_brand":[],"product_cat":[1300,1302,1303,664,1325,1265,1326,1267,1327,1268,1329,1269,1333,1270,1341,1271,1351,1275,1382,1279,1280,1283,1290,1296],"product_tag":[],"class_list":{"0":"post-3263","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-treatment-areas-vs-products-fr","7":"product_cat-buttocks-fr","8":"product_cat-legs-fr","9":"product_cat-uncategorized-fr","10":"product_cat-strech-marks-fr","11":"product_cat-melasmas-brown-spots-3-fr","12":"product_cat-stretch-marks-on-buttocks-fr","13":"product_cat-melasmas-brown-spots-7-fr","14":"product_cat-saggy-skin-6-fr","15":"product_cat-rough-skin-fr","16":"product_cat-melasmas-brown-spots-hyperpigmentation-fr","17":"product_cat-melasmas-brown-spots-5-fr","18":"product_cat-mesotherapy-products-fr","19":"product_cat-melasmas-brown-spots-6-fr","20":"product_cat-different-skin-tones-2-fr","21":"product_cat-melasmas-brown-spots-fr","22":"product_cat-improve-facial-contour-fr","23":"product_cat-melasmas-brown-spots-4-fr","24":"product_cat-biomimetic-products-fr","25":"product_cat-arms-fr","26":"product_cat-neck-fr","27":"product_cat-body-fr","28":"product_cat-face-fr","29":"product_cat-hands-fr","31":"first","32":"instock","33":"taxable","34":"shipping-taxable","35":"purchasable","36":"product-type-simple"},"acf":{"short_name":""},"_links":{"self":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product\/3263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/media\/8729"}],"wp:attachment":[{"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/media?parent=3263"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3263"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3263"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.therapmedic.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}